{"id":94,"date":"2015-07-23T10:43:21","date_gmt":"2015-07-23T08:43:21","guid":{"rendered":"http:\/\/inspirythemesdemo.com\/realplaces\/?post_type=property&#038;p=94"},"modified":"2022-10-05T19:08:56","modified_gmt":"2022-10-05T17:08:56","slug":"gesucht-einfamilienhaus-im-speckguertel-von-hh","status":"publish","type":"property","link":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/","title":{"rendered":"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH"},"content":{"rendered":"<p>Bei dieser Anzeige handelt es sich um den Suchauftrag eines unserer Kunden! Gesucht wird ein Haus im n\u00f6rdlichen Hamburger Speckg\u00fcrtel.<\/p>\n<p>Sollten Sie ein entsprechendes Objekt in gleichwertiger Lage und Preisklasse besitzen, w\u00fcrden wir uns sehr freuen Sie als Eigent\u00fcmer einmal pers\u00f6nlich kennenzulernen. Da wir f\u00fcr unsere Kunden &#8211; und nat\u00fcrlich auch f\u00fcr Sie &#8211; die bestm\u00f6gliche Vermittlung innerhalb k\u00fcrzester Zeit anstreben, wird Sie einer unserer professionellen Makler pers\u00f6nlich aufsuchen um die relevanten Daten Ihrer Immobilie aufzunehmen. Anschliessend wird er ein aussgekr\u00e4ftiges Expos\u00e8 f\u00fcr unsere Klienten erstellen und Ihre Immobilie auf unserer Unternehmensseite und weiteren Immobilienportalen ver\u00f6ffentlichen. Dieser Service ist f\u00fcr Sie als Eigent\u00fcmer\/Verk\u00e4ufer selbstverst\u00e4ndlich kostenlos und unverbindlich! Gern \u00fcbernehmen wir nat\u00fcrlich auch die komplette Vermarktung Ihrer Immobilie, so das Sie sich anschliessend um nichts mehr k\u00fcmmern m\u00fcssen.<\/p>\n<p>Sie suchen ebenfalls ein neues Eigenheim? Nutzen Sie einfach unseren<a href=\"https:\/\/lifestyle-immo24.de\/suchauftrag\/\"> Suchauftrag<\/a> oder kontaktieren Sie uns via <a href=\"https:\/\/lifestyle-immo24.de\/kontakt\/\">E-Mail <\/a>(info@lifestyle-immo24.de) oder <a href=\"https:\/\/lifestyle-immo24.de\/kontakt\/\">telefonisch (04123\/929262)<\/a>. Aufgrund unseres nationalen und internationalen Netzwerkes, k\u00f6nnen wir Ihnen interessante Objekte sowohl in Deutschland, wie auch im Ausland in k\u00fcrzester Zeit vermitteln.<\/p>\n<p>Ihnen gef\u00e4llt unsere Seite und Sie m\u00f6chten Ihre Immobilie gern selbst auf unserem Portal pr\u00e4sentieren? Auch kein Problem! Innerhalb weniger Minuten k\u00f6nnen Sie sich in unserem Mitgliederbereich registrieren, anmelden und anschliessend Ihre Immobilie mit allen erforderlichen Daten und Bildern einstellen. Momentan ist dieser Service f\u00fcr private Anzeigen noch kostenlos und es steht Ihnen dabei frei, Ihre Immobilie entweder provisionfrei von &#8220;Privat&#8221; anzubieten, oder einen unserer erfahrenen Makler f\u00fcr die Vermarktung Ihrer Immobilie &#8220;kostenlos&#8221; in Anspruch zu nehmen!<\/p>\n<p>Herzliche Gr\u00fcsse<\/p>\n<p>Ihr Michael Heinze &#8211; Immobilien Team<\/p>","protected":false},"excerpt":{"rendered":"<p>Bei dieser Anzeige handelt es sich um den Suchauftrag eines unserer Kunden! Gesucht wird ein Haus im n\u00f6rdlichen Hamburger Speckg\u00fcrtel. Sollten Sie ein entsprechendes Objekt in gleichwertiger Lage und Preisklasse besitzen, w\u00fcrden wir uns sehr freuen Sie als Eigent\u00fcmer einmal pers\u00f6nlich kennenzulernen. Da wir f\u00fcr unsere Kunden &#8211; und nat\u00fcrlich auch f\u00fcr Sie &#8211; die&#8230;<\/p>\n","protected":false},"author":1,"featured_media":97,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[16,22,29,399,839,36,21,405],"property-type":[203],"property-city":[],"property-status":[753],"class_list":["post-94","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-doppelgarage","property-feature-einbaukueche","property-feature-internet","property-feature-fire-place","property-feature-air-conditioning","property-feature-schwimmbad","property-feature-terrasse","property-feature-laundry-room","property-type-casa-chalet","property-status-verkauf"],"rvr_property_bookings":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes\" \/>\n<meta property=\"og:description\" content=\"Bei dieser Anzeige handelt es sich um den Suchauftrag eines unserer Kunden! Gesucht wird ein Haus im n\u00f6rdlichen Hamburger Speckg\u00fcrtel. Sollten Sie ein entsprechendes Objekt in gleichwertiger Lage und Preisklasse besitzen, w\u00fcrden wir uns sehr freuen Sie als Eigent\u00fcmer einmal pers\u00f6nlich kennenzulernen. Da wir f\u00fcr unsere Kunden &#8211; und nat\u00fcrlich auch f\u00fcr Sie &#8211; die...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestyle Homes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LifeStyleImmo24\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-05T17:08:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/\",\"name\":\"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/property-9.jpg\",\"datePublished\":\"2015-07-23T08:43:21+00:00\",\"dateModified\":\"2022-10-05T17:08:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/property-9.jpg\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/property-9.jpg\",\"width\":1000,\"height\":706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/gesucht-einfamilienhaus-im-speckguertel-von-hh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eigenschaften\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"name\":\"Lifestyle Homes\",\"description\":\"Casas de vacaciones en alquiler o en venta\",\"publisher\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\",\"name\":\"Lifestyle-Immo24\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"width\":1559,\"height\":482,\"caption\":\"Lifestyle-Immo24\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LifeStyleImmo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/","og_locale":"es_ES","og_type":"article","og_title":"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes","og_description":"Bei dieser Anzeige handelt es sich um den Suchauftrag eines unserer Kunden! Gesucht wird ein Haus im n\u00f6rdlichen Hamburger Speckg\u00fcrtel. Sollten Sie ein entsprechendes Objekt in gleichwertiger Lage und Preisklasse besitzen, w\u00fcrden wir uns sehr freuen Sie als Eigent\u00fcmer einmal pers\u00f6nlich kennenzulernen. Da wir f\u00fcr unsere Kunden &#8211; und nat\u00fcrlich auch f\u00fcr Sie &#8211; die...","og_url":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/","og_site_name":"Lifestyle Homes","article_publisher":"https:\/\/www.facebook.com\/LifeStyleImmo24\/","article_modified_time":"2022-10-05T17:08:56+00:00","og_image":[{"width":1000,"height":706,"url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/","url":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/","name":"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH &#8211; Lifestyle Homes","isPartOf":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/#primaryimage"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/#primaryimage"},"thumbnailUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg","datePublished":"2015-07-23T08:43:21+00:00","dateModified":"2022-10-05T17:08:56+00:00","breadcrumb":{"@id":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/#primaryimage","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg","width":1000,"height":706},{"@type":"BreadcrumbList","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/gesucht-einfamilienhaus-im-speckguertel-von-hh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lifestyle-immo24.de\/es\/"},{"@type":"ListItem","position":2,"name":"Eigenschaften","item":"https:\/\/lifestyle-immo24.de\/es\/property\/"},{"@type":"ListItem","position":3,"name":"GESUCHT: Einfamilienhaus im Speckg\u00fcrtel von HH"}]},{"@type":"WebSite","@id":"https:\/\/lifestyle-immo24.de\/es\/#website","url":"https:\/\/lifestyle-immo24.de\/es\/","name":"Lifestyle Homes","description":"Casas de vacaciones en alquiler o en venta","publisher":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifestyle-immo24.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lifestyle-immo24.de\/es\/#organization","name":"Lifestyle-Immo24","url":"https:\/\/lifestyle-immo24.de\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","width":1559,"height":482,"caption":"Lifestyle-Immo24"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LifeStyleImmo24\/"]}]}},"property_meta":{"REAL_HOMES_property_size":"ab 250","REAL_HOMES_property_size_postfix":"m\u00b2","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"5","REAL_HOMES_property_bathrooms":"2","REAL_HOMES_property_garage":"2","REAL_HOMES_property_id":"MH-2016-10","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_price":"740000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"max","rvr_bulk_pricing":[],"rvr_custom_reserved_dates":[],"rvr_seasonal_pricing":[],"rvr_additional_fees":[{"rvr_fee_type":"fixed","rvr_fee_calculation":"per_stay"}],"rvr_govt_tax":"","rvr_service_charges":"","rvr_guests_capacity":"","rvr_book_child_as":"","rvr_min_stay":"","rvr_guests_capacity_extend":"","rvr_extra_guest_price":"","rvr_accommodation":[],"rvr_instant_booking":"","rvr_property_owner":"0","rvr_outdoor_features":[],"rvr_surroundings":[],"rvr_included":[],"rvr_not_included":[],"rvr_policies":[],"rvr_import_icalendar_feed_list":[],"REAL_HOMES_property_location":{"latitude":"53.6639774","longitude":"9.905541","zoom":"14"},"REAL_HOMES_property_address":"B\u00f6nningstedt","REAL_HOMES_property_map":"","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2015\/07\/property-9.jpg","sizes":{"medium":{"file":"property-9-300x212.jpg","width":300,"height":212,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-300x212.jpg"},"thumbnail":{"file":"property-9-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-150x150.jpg"},"medium_large":{"file":"property-9-768x542.jpg","width":768,"height":542,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-768x542.jpg"},"post-thumbnail":{"file":"property-9-150x106.jpg","width":150,"height":106,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-150x106.jpg"},"modern-property-child-slider":{"file":"property-9-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-680x510.jpg"},"property-thumb-image":{"file":"property-9-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-488x326.jpg"},"property-detail-video-image":{"file":"property-9-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-818x417.jpg"},"agent-image":{"file":"property-9-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-210x210.jpg"},"partners-logo":{"file":"property-9-600x706.jpg","width":600,"height":706,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-600x706.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"97","name":"property-9.jpg","path":"\/homepages\/11\/d646231070\/htdocs\/clickandbuilds\/LifeStyleImmobilien\/wp-content\/uploads\/2015\/07\/property-9.jpg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-150x150.jpg","full_url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9.jpg","title":"property-9","caption":"","description":"","alt":"","srcset":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-150x150.jpg 150w, https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2015\/07\/property-9-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"https:\/\/www.youtube.com\/watch?v=fNStbC45uH4","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"my_profile_info","REAL_HOMES_agents":["-1"],"REAL_HOMES_energy_class":"none","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0","REAL_HOMES_custom_header_display":"default","REAL_HOMES_custom_header_position":"relative","REAL_HOMES_custom_footer_display":"default","REAL_HOMES_hide_advance_search":"0","REAL_HOMES_custom_search_form":"default","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":0,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property\/94\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/media\/97"}],"wp:attachment":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-feature?post=94"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-type?post=94"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-city?post=94"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-status?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}