{"id":19169,"date":"2020-12-07T15:29:54","date_gmt":"2020-12-07T14:29:54","guid":{"rendered":"https:\/\/lifestyle-immo24.de\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/"},"modified":"2022-11-15T13:55:59","modified_gmt":"2022-11-15T12:55:59","slug":"baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen","status":"publish","type":"property","link":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/","title":{"rendered":"Terreno edificable en La Galera de las Palmeras &#8211; Altea en venta"},"content":{"rendered":"<p><\/p>\n<p><\/p>\n<p>Se vende una parcela de 1.670 m2 en una de las mejores ubicaciones de Altea &#8211; Urb. Galera de las Palmeras. <\/p>\n<p>El terreno est\u00e1 situado en una zona muy tranquila y protegida en el mejor barrio y tiene vistas parciales al mar. Debido a su tama\u00f1o superior a la media, es ideal para la construcci\u00f3n de una villa moderna y espaciosa con piscina. <\/p>\n<p>La edificabilidad es del 25% de la superficie del terreno con un volumen de 0,8m3\/m2 para una casa unifamiliar de 2 plantas + s\u00f3tano. <\/p>\n<p>La parcela est\u00e1 completamente documentada y con planos levantados. Se dispone de un certificado de edificabilidad del municipio. <\/p>\n<p>Para m\u00e1s informaci\u00f3n o inspecci\u00f3n de la propiedad, por favor contacte con Clemens Hoffmann 0034 650 46 37 82 o info@real-estate-altea.com.[IW]<\/p>","protected":false},"excerpt":{"rendered":"<p>Se vende una parcela de 1.670 m2 en una de las mejores ubicaciones de Altea &#8211; Urb. Galera de las Palmeras. El terreno est\u00e1 situado en una zona muy tranquila y protegida en el mejor barrio y tiene vistas parciales al mar. Debido a su tama\u00f1o superior a la media, es ideal para la construcci\u00f3n&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19170,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[],"property-type":[232],"property-city":[748,747,620],"property-status":[753],"class_list":["post-19169","property","type-property","status-publish","has-post-thumbnail","hentry","property-type-parcela","property-city-altea","property-city-alicante","property-city-es","property-status-verkauf"],"rvr_property_bookings":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes\" \/>\n<meta property=\"og:description\" content=\"Se vende una parcela de 1.670 m2 en una de las mejores ubicaciones de Altea &#8211; Urb. Galera de las Palmeras. El terreno est\u00e1 situado en una zona muy tranquila y protegida en el mejor barrio y tiene vistas parciales al mar. Debido a su tama\u00f1o superior a la media, es ideal para la construcci\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestyle Homes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LifeStyleImmo24\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-15T12:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1919\" \/>\n\t<meta property=\"og:image:height\" content=\"1277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/\",\"name\":\"Baugrundst\u00fcck in La Galera de las Palmeras - Altea zu verkaufenBuilding plot in La Galera de las Palmeras - Altea for saleTerreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/img_3229.jpg\",\"datePublished\":\"2020-12-07T14:29:54+00:00\",\"dateModified\":\"2022-11-15T12:55:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/\"]]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/img_3229.jpg\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/img_3229.jpg\",\"width\":1919,\"height\":1277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eigenschaften\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baugrundst\u00fcck in La Galera de las Palmeras &#8211; Altea zu verkaufen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"name\":\"Lifestyle Homes\",\"description\":\"Casas de vacaciones en alquiler o en venta\",\"publisher\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\",\"name\":\"Lifestyle-Immo24\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"width\":1559,\"height\":482,\"caption\":\"Lifestyle-Immo24\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LifeStyleImmo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/","og_locale":"es_ES","og_type":"article","og_title":"Terreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes","og_description":"Se vende una parcela de 1.670 m2 en una de las mejores ubicaciones de Altea &#8211; Urb. Galera de las Palmeras. El terreno est\u00e1 situado en una zona muy tranquila y protegida en el mejor barrio y tiene vistas parciales al mar. Debido a su tama\u00f1o superior a la media, es ideal para la construcci\u00f3n...","og_url":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/","og_site_name":"Lifestyle Homes","article_publisher":"https:\/\/www.facebook.com\/LifeStyleImmo24\/","article_modified_time":"2022-11-15T12:55:59+00:00","og_image":[{"width":1919,"height":1277,"url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/","url":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/","name":"Baugrundst\u00fcck in La Galera de las Palmeras - Altea zu verkaufenBuilding plot in La Galera de las Palmeras - Altea for saleTerreno edificable en La Galera de las Palmeras - Altea en venta &#8211; Lifestyle Homes","isPartOf":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/#primaryimage"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/#primaryimage"},"thumbnailUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg","datePublished":"2020-12-07T14:29:54+00:00","dateModified":"2022-11-15T12:55:59+00:00","breadcrumb":{"@id":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/"]]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/#primaryimage","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg","width":1919,"height":1277},{"@type":"BreadcrumbList","@id":"https:\/\/lifestyle-immo24.de\/es\/property\/baugrundstueck-in-la-galera-de-las-palmeras-altea-zu-verkaufen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lifestyle-immo24.de\/es\/"},{"@type":"ListItem","position":2,"name":"Eigenschaften","item":"https:\/\/lifestyle-immo24.de\/es\/property\/"},{"@type":"ListItem","position":3,"name":"Baugrundst\u00fcck in La Galera de las Palmeras &#8211; Altea zu verkaufen"}]},{"@type":"WebSite","@id":"https:\/\/lifestyle-immo24.de\/es\/#website","url":"https:\/\/lifestyle-immo24.de\/es\/","name":"Lifestyle Homes","description":"Casas de vacaciones en alquiler o en venta","publisher":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifestyle-immo24.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lifestyle-immo24.de\/es\/#organization","name":"Lifestyle-Immo24","url":"https:\/\/lifestyle-immo24.de\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","width":1559,"height":482,"caption":"Lifestyle-Immo24"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LifeStyleImmo24\/"]}]}},"property_meta":{"REAL_HOMES_property_size":"\/","REAL_HOMES_property_size_postfix":"m\u00b2","REAL_HOMES_property_lot_size":"1670","REAL_HOMES_property_lot_size_postfix":"m\u00b2","REAL_HOMES_property_bedrooms":"","REAL_HOMES_property_bathrooms":"","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"PAR0018","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[["",""]],"REAL_HOMES_property_price":"248000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","rvr_bulk_pricing":[],"rvr_custom_reserved_dates":[],"rvr_seasonal_pricing":[],"rvr_additional_fees":[],"rvr_govt_tax":"","rvr_service_charges":"","rvr_guests_capacity":"","rvr_book_child_as":"","rvr_min_stay":"","rvr_guests_capacity_extend":"","rvr_extra_guest_price":"","rvr_accommodation":[],"rvr_instant_booking":"","rvr_property_owner":"","rvr_outdoor_features":[],"rvr_surroundings":[],"rvr_included":[],"rvr_not_included":[],"rvr_policies":[],"rvr_import_icalendar_feed_list":[],"REAL_HOMES_property_location":{"latitude":"38.6029075","longitude":"-0.0450666","zoom":""},"REAL_HOMES_property_address":"03599 Altea, , Alicante","REAL_HOMES_property_map":"Altea","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2020\/12\/img_3229.jpg","sizes":{"medium":{"file":"img_3229-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-300x200.jpg"},"large":{"file":"img_3229-1024x681.jpg","width":1024,"height":681,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-1024x681.jpg"},"thumbnail":{"file":"img_3229-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-150x150.jpg"},"medium_large":{"file":"img_3229-768x511.jpg","width":768,"height":511,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-768x511.jpg"},"1536x1536":{"file":"img_3229-1536x1022.jpg","width":1536,"height":1022,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-1536x1022.jpg"},"post-thumbnail":{"file":"img_3229-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-150x100.jpg"},"modern-property-child-slider":{"file":"img_3229-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-680x510.jpg"},"property-thumb-image":{"file":"img_3229-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-488x326.jpg"},"property-detail-video-image":{"file":"img_3229-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-818x417.jpg"},"agent-image":{"file":"img_3229-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-210x210.jpg"},"partners-logo":{"file":"img_3229-600x1277.jpg","width":600,"height":1277,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-600x1277.jpg"},"post-featured-image":{"file":"img_3229-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-1240x720.jpg"},"gallery-two-column-image":{"file":"img_3229-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-536x269.jpg"},"property-detail-slider-image-two":{"file":"img_3229-1170x648.jpg","width":1170,"height":648,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-1170x648.jpg"},"property-detail-slider-thumb":{"file":"img_3229-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-82x60.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"19170","name":"img_3229.jpg","path":"\/homepages\/11\/d646231070\/htdocs\/clickandbuilds\/LifeStyleImmobilien\/wp-content\/uploads\/2020\/12\/img_3229.jpg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-150x150.jpg","full_url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229.jpg","title":"img_3229","caption":"","description":"","alt":"","srcset":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-150x150.jpg 150w, https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3229-210x210.jpg 210w"},{"width":150,"height":150,"file":"2020\/12\/img_3228.jpg","sizes":{"medium":{"file":"img_3228-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-300x200.jpg"},"large":{"file":"img_3228-1024x681.jpg","width":1024,"height":681,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-1024x681.jpg"},"thumbnail":{"file":"img_3228-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-150x150.jpg"},"medium_large":{"file":"img_3228-768x511.jpg","width":768,"height":511,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-768x511.jpg"},"1536x1536":{"file":"img_3228-1536x1022.jpg","width":1536,"height":1022,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-1536x1022.jpg"},"post-thumbnail":{"file":"img_3228-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-150x100.jpg"},"modern-property-child-slider":{"file":"img_3228-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-680x510.jpg"},"property-thumb-image":{"file":"img_3228-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-488x326.jpg"},"property-detail-video-image":{"file":"img_3228-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-818x417.jpg"},"agent-image":{"file":"img_3228-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-210x210.jpg"},"partners-logo":{"file":"img_3228-600x1277.jpg","width":600,"height":1277,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-600x1277.jpg"},"post-featured-image":{"file":"img_3228-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-1240x720.jpg"},"gallery-two-column-image":{"file":"img_3228-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-536x269.jpg"},"property-detail-slider-image-two":{"file":"img_3228-1170x648.jpg","width":1170,"height":648,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-1170x648.jpg"},"property-detail-slider-thumb":{"file":"img_3228-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-82x60.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"19171","name":"img_3228.jpg","path":"\/homepages\/11\/d646231070\/htdocs\/clickandbuilds\/LifeStyleImmobilien\/wp-content\/uploads\/2020\/12\/img_3228.jpg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-150x150.jpg","full_url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228.jpg","title":"img_3228","caption":"","description":"","alt":"","srcset":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-150x150.jpg 150w, https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3228-210x210.jpg 210w"},{"width":150,"height":150,"file":"2020\/12\/img_3230.jpg","sizes":{"medium":{"file":"img_3230-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-300x200.jpg"},"large":{"file":"img_3230-1024x681.jpg","width":1024,"height":681,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-1024x681.jpg"},"thumbnail":{"file":"img_3230-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-150x150.jpg"},"medium_large":{"file":"img_3230-768x511.jpg","width":768,"height":511,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-768x511.jpg"},"1536x1536":{"file":"img_3230-1536x1022.jpg","width":1536,"height":1022,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-1536x1022.jpg"},"post-thumbnail":{"file":"img_3230-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-150x100.jpg"},"modern-property-child-slider":{"file":"img_3230-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-680x510.jpg"},"property-thumb-image":{"file":"img_3230-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-488x326.jpg"},"property-detail-video-image":{"file":"img_3230-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-818x417.jpg"},"agent-image":{"file":"img_3230-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-210x210.jpg"},"partners-logo":{"file":"img_3230-600x1277.jpg","width":600,"height":1277,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-600x1277.jpg"},"post-featured-image":{"file":"img_3230-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-1240x720.jpg"},"gallery-two-column-image":{"file":"img_3230-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-536x269.jpg"},"property-detail-slider-image-two":{"file":"img_3230-1170x648.jpg","width":1170,"height":648,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-1170x648.jpg"},"property-detail-slider-thumb":{"file":"img_3230-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-82x60.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ID":"19172","name":"img_3230.jpg","path":"\/homepages\/11\/d646231070\/htdocs\/clickandbuilds\/LifeStyleImmobilien\/wp-content\/uploads\/2020\/12\/img_3230.jpg","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-150x150.jpg","full_url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230.jpg","title":"img_3230","caption":"","description":"","alt":"","srcset":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-150x150.jpg 150w, https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2020\/12\/img_3230-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"","REAL_HOMES_gallery_slider_type":"thumb-on-bottom","inspiry_floor_plans":[{"inspiry_floor_plan_name":"http:\/\/www.real-estate-altea.com\/clients\/186\/property\/717265\/document\/plano-durotin.pdf"}],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"agent_info","REAL_HOMES_agents":["8803"],"REAL_HOMES_energy_class":"","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"","REAL_HOMES_custom_header_display":"","REAL_HOMES_custom_header_position":"","REAL_HOMES_custom_footer_display":"","REAL_HOMES_hide_advance_search":"","REAL_HOMES_custom_search_form":"","REAL_HOMES_search_form_margin_top":"","REAL_HOMES_search_form_margin_bottom":""},"_links":{"self":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property\/19169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/comments?post=19169"}],"version-history":[{"count":0,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property\/19169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/media\/19170"}],"wp:attachment":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/media?parent=19169"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-feature?post=19169"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-type?post=19169"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-city?post=19169"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/property-status?post=19169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}