{"id":954,"count":1,"description":"","link":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/","name":"National parks","slug":"national-parks","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>National parks Archive &#8211; Lifestyle Homes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"National parks Archive &#8211; Lifestyle Homes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestyle Homes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/category\\\/national-parks\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/category\\\/national-parks\\\/\",\"name\":\"National parks Archive &#8211; Lifestyle Homes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/category\\\/national-parks\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/category\\\/national-parks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"National parks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"name\":\"Lifestyle Homes\",\"description\":\"Casas de vacaciones en alquiler o en venta\",\"publisher\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#organization\",\"name\":\"Lifestyle-Immo24\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"width\":1559,\"height\":482,\"caption\":\"Lifestyle-Immo24\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LifeStyleImmo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"National parks Archive &#8211; Lifestyle Homes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/","og_locale":"es_ES","og_type":"article","og_title":"National parks Archive &#8211; Lifestyle Homes","og_url":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/","og_site_name":"Lifestyle Homes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/","url":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/","name":"National parks Archive &#8211; Lifestyle Homes","isPartOf":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#website"},"breadcrumb":{"@id":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lifestyle-immo24.de\/es\/category\/national-parks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lifestyle-immo24.de\/es\/"},{"@type":"ListItem","position":2,"name":"National parks"}]},{"@type":"WebSite","@id":"https:\/\/lifestyle-immo24.de\/es\/#website","url":"https:\/\/lifestyle-immo24.de\/es\/","name":"Lifestyle Homes","description":"Casas de vacaciones en alquiler o en venta","publisher":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifestyle-immo24.de\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lifestyle-immo24.de\/es\/#organization","name":"Lifestyle-Immo24","url":"https:\/\/lifestyle-immo24.de\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","width":1559,"height":482,"caption":"Lifestyle-Immo24"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LifeStyleImmo24\/"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/categories\/954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lifestyle-immo24.de\/es\/wp-json\/wp\/v2\/posts?categories=954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}