{"id":26589,"date":"2018-10-20T02:25:06","date_gmt":"2018-10-20T00:25:06","guid":{"rendered":"http:\/\/bookify24.com\/widerrufsbelehrung\/"},"modified":"2018-10-20T02:25:06","modified_gmt":"2018-10-20T00:25:06","slug":"widerrufsbelehrung","status":"publish","type":"page","link":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/","title":{"rendered":"Widerrufsbelehrung"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":190,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-26589","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Widerrufsbelehrung &#8211; Lifestyle Homes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Widerrufsbelehrung &#8211; Lifestyle Homes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestyle Homes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LifeStyleImmo24\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/widerrufsbelehrung\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/widerrufsbelehrung\\\/\",\"name\":\"Widerrufsbelehrung &#8211; Lifestyle Homes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#website\"},\"datePublished\":\"2018-10-20T00:25:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/widerrufsbelehrung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[[\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/widerrufsbelehrung\\\/\"]]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/widerrufsbelehrung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Widerrufsbelehrung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/\",\"name\":\"Lifestyle Homes\",\"description\":\"Holiday Homes for rent or for sale\",\"publisher\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#organization\",\"name\":\"Lifestyle-Immo24\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"contentUrl\":\"https:\\\/\\\/lifestyle-immo24.de\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/LOGO-Michael-Heinze-Immo-1.png\",\"width\":1559,\"height\":482,\"caption\":\"Lifestyle-Immo24\"},\"image\":{\"@id\":\"https:\\\/\\\/lifestyle-immo24.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LifeStyleImmo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Widerrufsbelehrung &#8211; Lifestyle Homes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/","og_locale":"en_US","og_type":"article","og_title":"Widerrufsbelehrung &#8211; Lifestyle Homes","og_url":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/","og_site_name":"Lifestyle Homes","article_publisher":"https:\/\/www.facebook.com\/LifeStyleImmo24\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/","url":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/","name":"Widerrufsbelehrung &#8211; Lifestyle Homes","isPartOf":{"@id":"https:\/\/lifestyle-immo24.de\/en\/#website"},"datePublished":"2018-10-20T00:25:06+00:00","breadcrumb":{"@id":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":[["https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/"]]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lifestyle-immo24.de\/en\/widerrufsbelehrung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lifestyle-immo24.de\/en\/"},{"@type":"ListItem","position":2,"name":"Widerrufsbelehrung"}]},{"@type":"WebSite","@id":"https:\/\/lifestyle-immo24.de\/en\/#website","url":"https:\/\/lifestyle-immo24.de\/en\/","name":"Lifestyle Homes","description":"Holiday Homes for rent or for sale","publisher":{"@id":"https:\/\/lifestyle-immo24.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lifestyle-immo24.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lifestyle-immo24.de\/en\/#organization","name":"Lifestyle-Immo24","url":"https:\/\/lifestyle-immo24.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lifestyle-immo24.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","contentUrl":"https:\/\/lifestyle-immo24.de\/wp-content\/uploads\/2017\/05\/LOGO-Michael-Heinze-Immo-1.png","width":1559,"height":482,"caption":"Lifestyle-Immo24"},"image":{"@id":"https:\/\/lifestyle-immo24.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LifeStyleImmo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/pages\/26589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/comments?post=26589"}],"version-history":[{"count":0,"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/pages\/26589\/revisions"}],"wp:attachment":[{"href":"https:\/\/lifestyle-immo24.de\/en\/wp-json\/wp\/v2\/media?parent=26589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}